{"id":5927,"date":"2020-04-09T09:00:56","date_gmt":"2020-04-09T08:00:56","guid":{"rendered":"https:\/\/www.d-edge.com\/hospitality-recovery-tracker\/"},"modified":"2020-07-20T09:25:52","modified_gmt":"2020-07-20T08:25:52","slug":"hospitality-recovery-tracker","status":"publish","type":"post","link":"https:\/\/www.d-edge.com\/de\/hospitality-recovery-tracker\/","title":{"rendered":"Hospitality Recovery Tracker"},"content":{"rendered":"<p>Das Hotelgesch\u00e4ft wird sich erholen. Die Frage ist: wann und in welchem Tempo?<br \/>\n Um Ihnen zu helfen, die ersten Anzeichen einer Erholung zu erkennen, haben wir diesen dynamischen Bericht erstellt, der die Buchungen und Stornierungen verfolgt, die \u00fcber unsere Systeme verarbeitet wurden. Sie k\u00f6nnen damit spielen und das Land und\/oder den jeweiligen Kanal (OTA\u00b4s, Wholesaler, Direktbucher) ausw\u00e4hlen, den Sie \u00fcberwachen m\u00f6chten.<br \/>\n Wir hoffen, dass diese Informationen Ihnen bei Ihrer Prognose helfen und Sie auf die Erholung des Gesch\u00e4fts am besten vorbereiten wird. Z\u00f6gern Sie nicht,<a href=\"https:\/\/www.d-edge.com\/de\/kontaktieren-sie-uns\/\">dies mit unserem Team zu besprechen und deren Hilfe und Rat einzuholen.<\/a>.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Das Hotelgesch\u00e4ft wird sich erholen. Die Frage ist: wann und in welchem Tempo? Um Ihnen zu helfen, die ersten Anzeichen einer Erholung zu erkennen, haben wir diesen dynamischen Bericht erstellt, der die Buchungen und Stornierungen verfolgt, die \u00fcber unsere Systeme verarbeitet wurden. Sie k\u00f6nnen damit spielen und das Land und\/oder den jeweiligen Kanal (OTA\u00b4s, Wholesaler, [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":5876,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[107],"tags":[],"class_list":["post-5927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-nachrichten"],"_links":{"self":[{"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/posts\/5927"}],"collection":[{"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/comments?post=5927"}],"version-history":[{"count":0,"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/posts\/5927\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/media\/5876"}],"wp:attachment":[{"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/media?parent=5927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/categories?post=5927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.d-edge.com\/de\/wp-json\/wp\/v2\/tags?post=5927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}