{"id":6060,"date":"2020-06-02T14:53:43","date_gmt":"2020-06-02T13:53:43","guid":{"rendered":"https:\/\/www.d-edge.com\/?p=6060"},"modified":"2024-10-28T15:42:20","modified_gmt":"2024-10-28T14:42:20","slug":"10-consejos-para-que-los-hoteleros-esten-listos-para-el-rebote","status":"publish","type":"post","link":"https:\/\/www.d-edge.com\/es\/10-consejos-para-que-los-hoteleros-esten-listos-para-el-rebote\/","title":{"rendered":"10 consejos para que los hoteleros est\u00e9n listos para el rebote"},"content":{"rendered":"<p>Como se muestra en nuestro Hospitality Recovery Tracker, <a href=\"https:\/\/www.d-edge.com\/es\/hospitality-recovery-tracker\/\" target=\"_blank\" rel=\"noopener noreferrer\"> la actividad del hotel est\u00e1 empezando a tener un buen comienzo en varios pa\u00edses<\/a>. Es hora de seguir esta din\u00e1mica y avanzar a una velocidad de crucero, teniendo en cuenta los profundos cambios que la epidemia de COVID-19 ha tenido en el sector.<\/p>\n<p>Para acompa\u00f1arles en este desaf\u00edo y prepararles mejor para su reapertura, hemos reunido las 10 acciones m\u00e1s importantes para implementar para su distribuci\u00f3n online:<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como se muestra en nuestro Hospitality Recovery Tracker, la actividad del hotel est\u00e1 empezando a tener un buen comienzo en varios pa\u00edses. Es hora de seguir esta din\u00e1mica y avanzar a una velocidad de crucero, teniendo en cuenta los profundos cambios que la epidemia de COVID-19 ha tenido en el sector. Para acompa\u00f1arles en este [&hellip;]<\/p>\n","protected":false},"author":5,"featured_media":6041,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[109],"tags":[],"class_list":["post-6060","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-noticias"],"_links":{"self":[{"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/posts\/6060"}],"collection":[{"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/users\/5"}],"replies":[{"embeddable":true,"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/comments?post=6060"}],"version-history":[{"count":0,"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/posts\/6060\/revisions"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/media\/6041"}],"wp:attachment":[{"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/media?parent=6060"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/categories?post=6060"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.d-edge.com\/es\/wp-json\/wp\/v2\/tags?post=6060"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}